{"id":175259,"date":"2025-07-14T10:14:36","date_gmt":"2025-07-14T08:14:36","guid":{"rendered":"https:\/\/hpx.eu\/product\/reinforced-aluminium-tape-8400\/"},"modified":"2025-07-14T10:38:13","modified_gmt":"2025-07-14T08:38:13","slug":"reinforced-aluminium-tape-8400","status":"publish","type":"product","link":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/","title":{"rendered":"REINFORCED ALUMINIUM TAPE <span class=\"productNr\">8400<\/span>"},"content":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<ul class=\"product_UPS\">\n<li>Cinta de aluminio reforzada con fibra de vidrio con baja permeabilidad al vapor de agua<\/li>\n<li>Adecuada para usos generales de reparaci\u00f3n, sellado y mantenimiento<\/li>\n<li>Acabado herm\u00e9tico al vapor y al aire de tuber\u00edas met\u00e1licas, paneles, conductos de ventilaci\u00f3n, etc.<\/li>\n<li><\/li>\n<li><\/li>\n<li><\/li>\n<li><\/li>\n<li><\/li>\n<li><\/li>\n<li><\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Cant.<\/th>\n<th>C\u00f3digo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>RA5050<\/td>\n<td>50 mm<\/td>\n<td>50 m<\/td>\n<td>aluminium<\/td>\n<td>24<\/td>\n<td>5407004564586<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n<p><b>Adhesivo: <\/b><span>acr\u00edlico solvente<\/span><\/p>\n<p><b>Soporte: <\/b><span>papel de aluminio reforzado con fibra de vidrio<\/span><\/p>\n<p><b>Temperatura m\u00e1xima: <\/b><span>120\u00b0C<\/span><\/p>\n<p><b>Resistencia a la tracci\u00f3n: <\/b><span>120 N\/25 mm<\/span><\/p>\n<p><b>Fuerza adhesiva: <\/b><span>25 N\/25 mm<\/span><\/p>\n<p><b>Resistencia al corte: <\/b><span><\/span><\/p>\n<p><b>Grosor: <\/b><span>0,05 mm<\/span><\/p>\n<p><b>Tensi\u00f3n de ruptura: <\/b><span><\/span><\/p>\n<\/p><\/div>\n<p>  <a href=\"https:\/\/drive.google.com\/uc?id=1YCG7n65hYt0j9zPsMNOyx3_7qFRbm49P&#038;export=download\" class=\"btnHPX\" target=\"_blank\"><i class=\"fa fa-download\" aria-hidden=\"true\"><\/i>Descargar ficha t\u00e9cnica (EN)<\/a><\/p>\n","protected":false},"featured_media":111785,"comment_status":"closed","ping_status":"open","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[1075],"product_tag":[],"class_list":{"0":"post-175259","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-especialidades","7":"post","8":"post-with-thumbnail","9":"post-with-thumbnail-large","11":"first","12":"instock","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REINFORCED ALUMINIUM TAPE | HPX<\/title>\n<meta name=\"description\" content=\"Cinta de aluminio reforzada con fibra de vidrio con baja permeabilidad al vapor de agua | Especialidades | REINFORCED ALUMINIUM TAPE | HPX\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REINFORCED ALUMINIUM TAPE | HPX\" \/>\n<meta property=\"og:description\" content=\"Cinta de aluminio reforzada con fibra de vidrio con baja permeabilidad al vapor de agua | Especialidades | REINFORCED ALUMINIUM TAPE | HPX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/\" \/>\n<meta property=\"og:site_name\" content=\"HPX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HPXtape\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T08:38:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hpx.eu\/wp-content\/uploads\/2022\/01\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/\",\"url\":\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/\",\"name\":\"REINFORCED ALUMINIUM TAPE | HPX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hpx.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg\",\"datePublished\":\"2025-07-14T08:14:36+00:00\",\"dateModified\":\"2025-07-14T08:38:13+00:00\",\"description\":\"Cinta de aluminio reforzada con fibra de vidrio con baja permeabilidad al vapor de agua | Especialidades | REINFORCED ALUMINIUM TAPE | HPX\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hpx.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg\",\"contentUrl\":\"https:\\\/\\\/hpx.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg\",\"width\":800,\"height\":800,\"caption\":\"REINFORCED ALUMINIUM TAPE | HPX\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/product\\\/reinforced-aluminium-tape-8400\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hpx.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"http:\\\/\\\/hpx.eu\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"REINFORCED ALUMINIUM TAPE 8400\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/hpx.eu\\\/es\\\/\",\"name\":\"HPX\",\"description\":\"Tough Job, Tougher Tape\",\"publisher\":{\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/hpx.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#organization\",\"name\":\"Option Tape Specialties\",\"url\":\"http:\\\/\\\/hpx.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Option Tape Specialties\"},\"image\":{\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HPXtape\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2913311\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCCYnFjBGfKw8SPW1hMUCVFg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REINFORCED ALUMINIUM TAPE | HPX","description":"Cinta de aluminio reforzada con fibra de vidrio con baja permeabilidad al vapor de agua | Especialidades | REINFORCED ALUMINIUM TAPE | HPX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/","og_locale":"es_ES","og_type":"article","og_title":"REINFORCED ALUMINIUM TAPE | HPX","og_description":"Cinta de aluminio reforzada con fibra de vidrio con baja permeabilidad al vapor de agua | Especialidades | REINFORCED ALUMINIUM TAPE | HPX","og_url":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/","og_site_name":"HPX","article_publisher":"https:\/\/www.facebook.com\/HPXtape\/","article_modified_time":"2025-07-14T08:38:13+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/hpx.eu\/wp-content\/uploads\/2022\/01\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/","url":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/","name":"REINFORCED ALUMINIUM TAPE | HPX","isPartOf":{"@id":"https:\/\/hpx.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/#primaryimage"},"image":{"@id":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/#primaryimage"},"thumbnailUrl":"https:\/\/hpx.eu\/wp-content\/uploads\/2022\/01\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg","datePublished":"2025-07-14T08:14:36+00:00","dateModified":"2025-07-14T08:38:13+00:00","description":"Cinta de aluminio reforzada con fibra de vidrio con baja permeabilidad al vapor de agua | Especialidades | REINFORCED ALUMINIUM TAPE | HPX","breadcrumb":{"@id":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/#primaryimage","url":"https:\/\/hpx.eu\/wp-content\/uploads\/2022\/01\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg","contentUrl":"https:\/\/hpx.eu\/wp-content\/uploads\/2022\/01\/RA5050-Reinforced_aluminium_tape-50mm_x_50m-5407004564586.jpg","width":800,"height":800,"caption":"REINFORCED ALUMINIUM TAPE | HPX"},{"@type":"BreadcrumbList","@id":"https:\/\/hpx.eu\/es\/product\/reinforced-aluminium-tape-8400\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hpx.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/hpx.eu\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"REINFORCED ALUMINIUM TAPE 8400"}]},{"@type":"WebSite","@id":"https:\/\/hpx.eu\/es\/#website","url":"https:\/\/hpx.eu\/es\/","name":"HPX","description":"Tough Job, Tougher Tape","publisher":{"@id":"https:\/\/hpx.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hpx.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hpx.eu\/es\/#organization","name":"Option Tape Specialties","url":"https:\/\/hpx.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hpx.eu\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Option Tape Specialties"},"image":{"@id":"https:\/\/hpx.eu\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HPXtape\/","https:\/\/www.linkedin.com\/company\/2913311\/","https:\/\/www.youtube.com\/channel\/UCCYnFjBGfKw8SPW1hMUCVFg"]}]}},"_links":{"self":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/product\/175259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/comments?post=175259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/media\/111785"}],"wp:attachment":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/media?parent=175259"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/product_brand?post=175259"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/product_cat?post=175259"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/product_tag?post=175259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}