{"id":108617,"date":"2021-05-20T15:48:40","date_gmt":"2021-05-20T13:48:40","guid":{"rendered":"https:\/\/hpx.eu\/?page_id=108617"},"modified":"2025-10-24T09:34:02","modified_gmt":"2025-10-24T07:34:02","slug":"durable-airtight-products","status":"publish","type":"page","link":"https:\/\/hpx.eu\/es\/durable-airtight-products\/","title":{"rendered":"DURABLE AIRTIGHT PRODUCTS"},"content":{"rendered":"<div id=\"AIRTIGHT\">\n<h1>DURABLE AIRTIGHT PRODUCTS<\/h1>\n<p>  <img decoding=\"async\" id=\"mobileOverview\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/mobileOverview-2025.jpg\" alt=\"Durable Airtight Products - Overview\" usemap=\"#mobileDAP\" \/><\/p>\n<map name=\"mobileDAP\">\n<area coords=\"39,672,619,952\" shape=\"rect\" href=\"#flex\" \/>\n<area coords=\"39,988,619,1268\" shape=\"rect\" href=\"#flexGo\" \/>\n<area coords=\"39,1304,619,1584\" shape=\"rect\" href=\"#roof\" \/>\n<area coords=\"39,1620,619,1900\" shape=\"rect\" href=\"#uv\" \/>\n<area coords=\"39,1936,619,2216\" shape=\"rect\" href=\"#indoor\" \/>\n<area coords=\"39,2252,619,2532\" shape=\"rect\" href=\"#fix\" \/>\n  <\/map>\n<div id=\"overview\">\n<ul>\n<li><a href=\"#flex\" class=\"flex\" title=\"AIRTIGHT Flex\"><span>AIRTIGHT Flex<\/span><\/a><\/li>\n<li><a href=\"#flex\" class=\"flex2\" title=\"AIRTIGHT Flex\"><span>AIRTIGHT Flex<\/span><\/a><\/li>\n<li><a href=\"#flexGo\" class=\"flex3\" title=\"AIRTIGHT Flex Go\"><span>AIRTIGHT Flex Go<\/span><\/a><\/li>\n<li><a href=\"#flexGo\" class=\"flex4\" title=\"AIRTIGHT Flex Go\"><span>AIRTIGHT Flex Go<\/span><\/a><\/li>\n<li><a href=\"#uv\" class=\"uv\" title=\"AIRTIGHT UV\"><span>AIRTIGHT UV<\/span><\/a><\/li>\n<li><a href=\"#uv\" class=\"uv2\" title=\"AIRTIGHT UV\"><span>AIRTIGHT UV<\/span><\/a><\/li>\n<li><a href=\"#uv\" class=\"uv3\" title=\"AIRTIGHT UV\"><span>AIRTIGHT UV<\/span><\/a><\/li>\n<li><a href=\"#indoor\" class=\"indoor\" title=\"AIRTIGHT Indoor\"><span>AIRTIGHT Indoor<\/span><\/a><\/li>\n<li><a href=\"#indoor\" class=\"indoor2\" title=\"AIRTIGHT Indoor\"><span>AIRTIGHT Indoor<\/span><\/a><\/li>\n<li><a href=\"#roof\" class=\"roof\" title=\"AIRTIGHT Roof\"><span>AIRTIGHT Roof<\/span><\/a><\/li>\n<li><a href=\"#fix\" class=\"fix\" title=\"AIRTIGHT Fix\"><span>AIRTIGHT Fix<\/span><\/a><\/li>\n<\/ul>\n<div id=\"tooltip\">\n<div id=\"TT_flex\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-Chimney.jpg\" \/><\/p>\n<h4>AIRTIGHT FLEX<\/h4>\n<\/div>\n<div id=\"TT_flex2\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-OSB.jpg\" \/><\/p>\n<h4>AIRTIGHT FLEX<\/h4>\n<\/div>\n<div id=\"TT_flex3\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_go-Ceiling.jpg\" \/><\/p>\n<h4>AIRTIGHT FLEX GO<\/h4>\n<\/div>\n<div id=\"TT_flex4\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_Go-Window.jpg\" \/><\/p>\n<h4>AIRTIGHT FLEX GO<\/h4>\n<\/div>\n<div id=\"TT_uv\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Wall.jpg\" \/><\/p>\n<h4>AIRTIGHT UV<\/h4>\n<\/div>\n<div id=\"TT_uv2\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Chimney.jpg\" \/><\/p>\n<h4>AIRTIGHT UV<\/h4>\n<\/div>\n<div id=\"TT_uv3\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Roof_window.jpg\" \/><\/p>\n<h4>AIRTIGHT UV<\/h4>\n<\/div>\n<div id=\"TT_indoor\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Indoor.jpg\" \/><\/p>\n<h4>AIRTIGHT INDOOR<\/h4>\n<\/div>\n<div id=\"TT_indoor2\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Indoor.jpg\" \/><\/p>\n<h4>AIRTIGHT INDOOR<\/h4>\n<\/div>\n<div id=\"TT_roof\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Roof.jpg\" \/><\/p>\n<h4>AIRTIGHT ROOF<\/h4>\n<\/div>\n<div id=\"TT_fix\"><img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Fix.jpg\" \/><\/p>\n<h4>AIRTIGHT FIX<\/h4>\n<\/div><\/div>\n<\/div>\n<h2>\u00bfPor qu\u00e9 construir de forma herm\u00e9tica con los productos herm\u00e9ticos y duraderos de HPX?<\/h2>\n<p>  Pasamos la mayor parte del tiempo en interiores. Por ello, la calidad del aire en nuestros hogares y lugares de trabajo es esencial para nuestra salud y bienestar. Adem\u00e1s, con la construcci\u00f3n herm\u00e9tica queremos reducir la p\u00e9rdida de energ\u00eda al m\u00ednimo. Sin embargo, las peque\u00f1as aberturas y grietas en el edificio pueden permitir la entrada de aire a trav\u00e9s del aislamiento. Esto no solo reduce el potencial de ahorro de energ\u00eda mediante el aislamiento, sino que tambi\u00e9n puede causar humedad penetrante, lo que puede provocar la formaci\u00f3n de moho o condensaci\u00f3n. Por tanto, no basta con un aislamiento correcto.<\/p>\n<p>El sellado adecuado de huecos y aberturas con productos herm\u00e9ticos y duraderos de HPX reduce la p\u00e9rdida de calor hasta en un 25 %. Adem\u00e1s, estos productos cumplen con la clase de emisi\u00f3n EMICODE EC1. Este certificado se concede a los productos de construcci\u00f3n que contribuyen a una calidad del aire interior segura y con bajas emisiones. Sin flujos de aire indeseables, el aire no debe enfriarse en verano ni calentarse en invierno. Una envoltura herm\u00e9tica del edificio garantiza un aislamiento eficaz y una ventilaci\u00f3n controlada, lo que se traduce en una menor factura energ\u00e9tica y una mejor calidad del aire.<\/p>\n<p><b>Los productos herm\u00e9ticos y duraderos de HPX<\/b><\/p>\n<ul>\n<li>crean un entorno de vida saludable<\/li>\n<li>contribuyen a un consumo energ\u00e9tico eficiente<\/li>\n<li>aumentan el confort interior evitando las corrientes de aire <\/li>\n<li>se pueden utilizar en combinaci\u00f3n con todas las barreras de vapor habituales y otros materiales de construcci\u00f3n<\/li>\n<li>son f\u00e1ciles de usar<\/li>\n<li>tienen una larga vida \u00fatil garantizada<\/li>\n<\/ul>\n<p>  <img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT-p2.jpg\" \/><\/p>\n<h2>Una gama completa de productos para el sellado y la adhesi\u00f3n de barreras de vapor, membranas y otros materiales de construcci\u00f3n en el interior de la vivienda<\/h2>\n<p>  Los productos herm\u00e9ticos y duraderos de HPX son una selecci\u00f3n de cintas autoadhesivas profesionales para el sellado de viviendas y edificios.<br \/>\nEl sistema incluye productos para interiores y exteriores, as\u00ed como para zonas dif\u00edciles de sellar. <img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/09\/AIRTIGHT_products.jpg\" \/><\/p>\n<h2>CERTIFICADOS Y DURABILIDAD<\/h2>\n<p> Los productos herm\u00e9ticos y duraderos de HPX est\u00e1n dise\u00f1adas para ser muy resistentes al paso del tiempo y son duraderos. Cumplen con la norma <b>DIN 4108-11<\/b>, lo que significa que estas cintas autoadhesivas cumplen los requisitos de fuerza de adhesi\u00f3n duradera que tienen como resultado capas herm\u00e9ticas.<\/p>\n<p>Los productos herm\u00e9ticos y duraderos de HPX tambi\u00e9n cumplen los estrictos requisitos de la norma <b>DIN 4108-7<\/b>. Son adecuados para el sellado permanente de barreras de vapor, un requisito esencial dentro de este campo de aplicaci\u00f3n. <\/p>\n<p>HPX siempre busca productos que contribuyan a una mejor calidad de vida. Por eso, nuestros productos herm\u00e9ticos y duraderos de HPX llevan la etiqueta <b>EMICODE EC 1<\/b>. Los productos con esta etiqueta emiten pocas emisiones y contribuyen a una calidad del aire interior buena y segura, tambi\u00e9n a largo plazo. <\/p>\n<p>Todas nuestras cintas se han probado en condiciones reales y funcionan perfectamente en combinaci\u00f3n con todas las barreras de vapor habituales y otros materiales de construcci\u00f3n.<img decoding=\"async\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/certificates.jpg\" \/><\/p>\n<div class=\"body\">\n<hr id=\"flexGo\" \/>\n    <img decoding=\"async\" class=\"productImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/06\/AN6025-8550-Airtight_Flex_Go-white-60_mm-25_m-5407004567181-1.jpg\" \/><\/p>\n<h2>AIRTIGHT FLEX GO<\/h2>\n<div class=\"applications\"><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT_Flex_Go-Detail_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT_Flex_Go-Detail_2.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_Go-Window.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_Go-Window.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_go-Ceiling.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_go-Ceiling.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_Go-OSB.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/AIRTIGHT-Flex_Go-OSB.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><\/div>\n<ul class=\"product_UPS\">\n<li>Cinta de polietileno flexible de una cara sin revestimiento antiadherente<\/li>\n<li>Sellado herm\u00e9tico y duradero de juntas y puntos de penetraci\u00f3n en barreras de vapor y otras conexiones interiores<\/li>\n<li>Sin liner para una aplicaci\u00f3n m\u00e1s f\u00e1cil y r\u00e1pida y menos residuos de embalaje<\/li>\n<li>Buena adherencia a superficies no polares y de baja energ\u00eda (LSE)<\/li>\n<li>Aplicable a temperaturas de hasta -10\u00b0C (idealmente entre 5\u00b0C y 35\u00b0C)<\/li>\n<li>DIN 4108\/7 y DIN 4108\/11<\/li>\n<li>Emicode EC1 plus<\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Paq.<\/th>\n<th>Codigo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>AN6025<\/td>\n<td>60 mm<\/td>\n<td>25 m<\/td>\n<td>blanco<\/td>\n<td>24<\/td>\n<td>5407004567181<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n        <b>Adhesivo: <\/b>acrilico<br \/>\n        <b>Soporte: <\/b>pel\u00edcula de polietileno de baja densidad (LDPE) reforzada con tela met\u00e1lica para su estabilizaci\u00f3n<br \/>\n        <b>Fuerza adhesiva: <\/b>\u2265 25 N\/25 mm<br \/>\n        <b>Grosor: <\/b>0,25 mm<br \/>\n        <b>Resistencia a la temperatura: <\/b>de -30 \u00b0C a +100 \u00b0C<br \/>\n        <b>Resistencia a la humedad: <\/b>alta<br \/>\n        <b>Resistencia al paso del tiempo: <\/b>muy alta\n    <\/div>\n<hr id=\"flex\" \/>\n    <img decoding=\"async\" class=\"productImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/IS6025-Airtight_Flex-green-60mm_x_25m-5425014228465-LR.jpg\" \/><\/p>\n<h2>AIRTIGHT FLEX<\/h2>\n<div class=\"applications\"><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Flex-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Flex-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-Chimney.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-Chimney.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-Beam.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-Beam.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-Window.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-Window.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-OSB.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Flex-OSB.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><\/div>\n<ul class=\"product_UPS\">\n<li>Cinta de polietileno flexible de una sola cara para usarla en interiores<\/li>\n<li>Adecuado para sellar y cubrir solapamientos de barreras de vapor<\/li>\n<li>Sellado herm\u00e9tico de penetraciones (por ejemplo, cables, tuber\u00edas, tubos, &#8230;) y otras conexiones<\/li>\n<li>Para sellar las esquinas en el interior de los tejados inclinados<\/li>\n<li>Para sellar las juntas de los paneles OSB y DWD<\/li>\n<li>DIN 4108\/7 y DIN 4108\/11<\/li>\n<li>EMICODE EC1 plus<\/li>\n<\/ul>\n<ul class=\"secondary_USPs\">\n<li>Resistencia superior al paso del tiempo <\/li>\n<li>Sin disolventes<\/li>\n<li>Para un sellado flexible<\/li>\n<li>Adherencia ideal a los materiales de construcci\u00f3n m\u00e1s utilizados (LSE) como madera contrachapada, barreras de vapor, PE, PP, PTFE y materiales no tejidos<\/li>\n<li>Aplicaci\u00f3n r\u00e1pida y sencilla durante todo el a\u00f1o<\/li>\n<li>Temperatura de servicio: -10 \u00b0C (idealmente entre 5 \u00b0C y 35 \u00b0C)<\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Paq.<\/th>\n<th>Codigo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>IS5025<\/td>\n<td>50 mm<\/td>\n<td>25 m<\/td>\n<td>verde<\/td>\n<td>30<\/td>\n<td>5407004560076<\/td>\n<\/tr>\n<tr>\n<td>IS6025<\/td>\n<td>60 mm<\/td>\n<td>25 m<\/td>\n<td>verde<\/td>\n<td>24<\/td>\n<td>5425014228465<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n        <b>Adhesivo: <\/b>acrilico<br \/>\n        <b>Soporte: <\/b>pel\u00edcula de polietileno de baja densidad (LDPE) reforzada con tela met\u00e1lica para su estabilizaci\u00f3n<br \/>\n        <b>Revestimiento: <\/b>papel recubierto de silicona<br \/>\n        <b>Fuerza adhesiva: <\/b>\u2265 25 N\/25 mm<br \/>\n        <b>Grosor: <\/b>0,25 mm<br \/>\n        <b>Resistencia a la temperatura: <\/b>de -30 \u00b0C a +100 \u00b0C<br \/>\n        <b>Resistencia a la humedad: <\/b>alta<br \/>\n        <b>Resistencia al paso del tiempo: <\/b>muy alta\n    <\/div>\n<hr id=\"uv\" \/>\n    <img decoding=\"async\" class=\"productImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/US6025-Airtight_UV-black-60mm_x_25m-5407004563299-LR.jpg\" \/><\/p>\n<h2>AIRTIGHT UV<\/h2>\n<div class=\"applications\"><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_UV-Wall-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_UV-Wall-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_UV-Chimney-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_UV-Chimney-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Chimney.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Chimney.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Roof_window.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Roof_window.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Wall.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-UV-Wall.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/UVx025-Isoseal_Black_UV-Applications.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/UVx025-Isoseal_Black_UV-Applications.jpg\" alt=\"\" width=\"568\" height=\"567\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><\/div>\n<ul class=\"product_UPS\">\n<li>Cinta de polietileno flexible y resistente a los rayos UV para usarla en exteriores<\/li>\n<li>Sellado y pegado invisible de solapamiento para un laminado resistente a la intemperie de l\u00e1minas para fachadas exteriores<\/li>\n<li>Para fachadas (semi)abiertas<\/li>\n<li>Completamente impermeable, evita la condensaci\u00f3n en el edificio<\/li>\n<li>DIN 4108\/7 y DIN 4108\/11<\/li>\n<\/ul>\n<ul class=\"secondary_USPs\">\n<li>Resistencia superior al paso del tiempo en las membranas de fachada (negras) (estables frente a los rayos UV)<\/li>\n<li>Sin disolventes<\/li>\n<li>Sellado flexible y el\u00e1stico, incluso con movimientos estructurales<\/li>\n<li>Adherencia ideal a los materiales de construcci\u00f3n m\u00e1s utilizados (LSE) como madera contrachapada, barreras de vapor, PE, PP, PTFE y materiales no tejidos<\/li>\n<li>Aplicaci\u00f3n r\u00e1pida y sencilla durante todo el a\u00f1o<\/li>\n<li>Temperatura de servicio: -10 \u00b0C (idealmente entre 5 \u00b0C y 35 \u00b0C)<\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Paq.<\/th>\n<th>Codigo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>US6025<\/td>\n<td>60 mm<\/td>\n<td>25 m<\/td>\n<td>negro<\/td>\n<td>24<\/td>\n<td>5407004563299<\/td>\n<\/tr>\n<tr>\n<td>US9025<\/td>\n<td>90 mm<\/td>\n<td>25 m<\/td>\n<td>negro<\/td>\n<td>12<\/td>\n<td>5407004563312<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n        <b>Adhesivo: <\/b>acrilico<br \/>\n        <b>Soporte: <\/b>pel\u00edcula de polietileno de baja densidad (LDPE) reforzada con tela met\u00e1lica para su estabilizaci\u00f3n<br \/>\n        <b>Revestimiento: <\/b>papel recubierto de silicona<br \/>\n        <b>Fuerza adhesiva: <\/b>25 N\/25 mm<br \/>\n        <b>Grosor: <\/b>0,27 mm<br \/>\n        <b>Resistencia a la temperatura: <\/b>de -30 \u00b0C a +100 \u00b0C<br \/>\n        <b>Resistencia a la humedad: <\/b>alta<br \/>\n        <b>Resistencia al paso del tiempo: <\/b>muy alta<br \/>\n        <b>Resistencia a los rayos UV: <\/b>muy alta\n    <\/div>\n<hr id=\"indoor\" \/>\n    <img decoding=\"async\" class=\"productImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AI6025-Airtight_Indoor-yellow-60mm_x_25m-5407004563961-LR.jpg\" \/><\/p>\n<h2>AIRTIGHT INDOOR<\/h2>\n<div class=\"applications\"><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Indoor-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Indoor-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Indoor-Detail_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Indoor-Detail_2.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Indoor.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Indoor.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Indoor-Attic-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Indoor-Attic-1.jpg\" alt=\"\" width=\"1000\" height=\"1000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Indoor-Ceiling-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Indoor-Ceiling-1.jpg\" alt=\"\" width=\"1000\" height=\"1000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><\/div>\n<ul class=\"product_UPS\">\n<li>Cinta de sellado de papel para uso en interiores<\/li>\n<li>Para el encolado cruzado de membranas y barreras de vapor<\/li>\n<li>Para sellar las juntas de los paneles OSB<\/li>\n<li>Para cubrir las grapas despu\u00e9s de instalar las barreras de vapor<\/li>\n<li>Para el aislamiento t\u00e9rmico en proyectos de tejados e interiores<\/li>\n<li>DIN 4108\/7 y DIN 4108\/11<\/li>\n<li>EMICODE EC1 plus<\/li>\n<\/ul>\n<ul class=\"secondary_USPs\">\n<li>Resistencia superior al paso del tiempo <\/li>\n<li>Sin disolventes<\/li>\n<li>Resistente al estiramiento para una aplicaci\u00f3n eficaz<\/li>\n<li>Se puede cortar a mano<\/li>\n<li>Adherencia ideal a los materiales de construcci\u00f3n m\u00e1s utilizados (LSE) como madera contrachapada, barreras de vapor, PE, PP, PTFE y materiales no tejidos<\/li>\n<li>Aplicaci\u00f3n r\u00e1pida y sencilla durante todo el a\u00f1o<\/li>\n<li>Temperatura de servicio: -10 \u00b0C (idealmente entre 5 \u00b0C y 35 \u00b0C)<\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Paq.<\/th>\n<th>Codigo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>AI6025<\/td>\n<td>60 mm<\/td>\n<td>25 m<\/td>\n<td>amarillo<\/td>\n<td>24<\/td>\n<td>5407004563961<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n        <b>Adhesivo: <\/b>acrilico<br \/>\n        <b>Soporte: <\/b>papel madera recubierto de PE<br \/>\n        <b>Revestimiento: <\/b>polietileno de baja densidad<br \/>\n        <b>Fuerza adhesiva: <\/b>25 N\/25 mm<br \/>\n        <b>Grosor: <\/b>0,27 mm<br \/>\n        <b>Resistencia a la temperatura: <\/b>de -30 \u00b0C a +100 \u00b0C<br \/>\n        <b>Resistencia a la humedad: <\/b>alta<br \/>\n        <b>Resistencia al paso del tiempo: <\/b>muy alta\n    <\/div>\n<hr id=\"roof\" \/>\n    <img decoding=\"async\" class=\"productImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AR6025-Airtight_Roof-grey-60mm_x_25m-5407004563985-LR.jpg\" \/><\/p>\n<h2>AIRTIGHT ROOF<\/h2>\n<div class=\"applications\"><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Roof-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Roof-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Roof-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Roof-2.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Roof.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Roof.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Roof-3-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Roof-3-1.jpg\" alt=\"\" width=\"1000\" height=\"1000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Roof-4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT_Roof-4-1.jpg\" alt=\"\" width=\"1000\" height=\"1000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Emicode_EC1.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"cert alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/DIN.jpg\" alt=\"\" width=\"332\" height=\"332\" \/><\/a><\/div>\n<ul class=\"product_UPS\">\n<li>Cinta selladora y adhesiva para proteger del viento y la lluvia las capas base de techos inclinados<\/li>\n<li>Se puede aplicar yeso por encima<\/li>\n<li>Resiste bien a la expansi\u00f3n t\u00e9rmica y al movimiento del edificio<\/li>\n<li>La cinta de polipropileno hilada protege contra la humedad y el vapor, lo que aumenta la vida \u00fatil de los materiales de construcci\u00f3n<\/li>\n<li>Aseguramiento y sellado de solapamientos de, entre otros, sustratos lisos y no minerales (tanto en interiores como en exteriores)<\/li>\n<li>DIN 4108\/7 y DIN 4108\/11<\/li>\n<li>EMICODE EC1 plus<\/li>\n<\/ul>\n<ul class=\"secondary_USPs\">\n<li>Resistencia superior al paso del tiempo <\/li>\n<li>Sin disolventes<\/li>\n<li>Resistente al estiramiento para una aplicaci\u00f3n eficaz<\/li>\n<li>Adherencia ideal a los materiales de construcci\u00f3n m\u00e1s utilizados (LSE) como madera contrachapada, barreras de vapor, PE, PP, PTFE y materiales no tejidos<\/li>\n<li>Aplicaci\u00f3n r\u00e1pida y sencilla durante todo el a\u00f1o<\/li>\n<li>Temperatura de servicio: -10 \u00b0C (idealmente entre 5 \u00b0C y 35 \u00b0C)<\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Paq.<\/th>\n<th>Codigo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>AR6025<\/td>\n<td>60 mm<\/td>\n<td>25 m<\/td>\n<td>gris<\/td>\n<td>24<\/td>\n<td>5407004563985<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n        <b>Adhesivo: <\/b>acrilico<br \/>\n        <b>Soporte:\u00a0pel\u00edcula de polietileno de baja densidad (LDPE) reforzada con tela met\u00e1lica para su estabilizaci\u00f3n<\/b><br \/>\n        <b>Revestimiento: <\/b>papel recubierto de silicona<br \/>\n        <b>Fuerza adhesiva: <\/b>30 N\/25 mm<br \/>\n        <b>Grosor: <\/b>0,55 mm<br \/>\n        <b>Resistencia a la temperatura: <\/b>de -30 \u00b0C a +100 \u00b0C<br \/>\n        <b>Resistencia a la humedad: <\/b>alta<br \/>\n        <b>Resistencia al paso del tiempo: <\/b>muy alta\n    <\/div>\n<hr id=\"fix\" \/>\n    <img decoding=\"async\" class=\"productImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AF3850-Airtight_Fix-transparent-38mm_x_50m-5407004564005-LR.jpg\" \/><\/p>\n<h2>AIRTIGHT FIX<\/h2>\n<div class=\"applications\"><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Fix-Metal-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Fix-Metal-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Fix-Wood-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Fix-Wood-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Fix-Metal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT_Fix-Metal.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Fix.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/04\/AIRTIGHT-Fix.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT-Fix-3-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT-Fix-3-1.jpg\" alt=\"\" width=\"1000\" height=\"1000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT-Fix-4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/AIRTIGHT-Fix-4-1.jpg\" alt=\"\" width=\"1000\" height=\"1000\" \/><\/a><\/div>\n<ul class=\"product_UPS\">\n<li>Cinta de doble cara con malla reforzada<\/li>\n<li>Para montar barreras de vapor en estructuras met\u00e1licas y de madera.<\/li>\n<\/ul>\n<ul class=\"secondary_USPs\">\n<li>Fuerza adhesiva muy elevada<\/li>\n<li>Buena adhesi\u00f3n a PE, PA, aluminio, papel madera, metal, pl\u00e1stico, OSB y materiales de madera<\/li>\n<li>En la superficie no debe haber polvo ni grasa<\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Paq.<\/th>\n<th>Codigo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>AF3850<\/td>\n<td>38 mm<\/td>\n<td>50 m<\/td>\n<td>transparente<\/td>\n<td>24<\/td>\n<td>5407004564005<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n        <b>Adhesivo: <\/b>acrilico<br \/>\n        <b>Soporte:\u00a0malla de poli\u00e9ster<\/b><br \/>\n        <b>Revestimiento: <\/b>papel recubierto de silicona<br \/>\n        <b>Fuerza adhesiva: <\/b>30 N\/25 mm<br \/>\n        <b>Grosor: <\/b>0,22 mm<br \/>\n        <b>Resistencia a la temperatura: <\/b>120 \u00b0C\n    <\/div>\n<p>    <img decoding=\"async\" class=\"endImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2022\/04\/AIRTIGHT-p6.jpg\" \/> <img decoding=\"async\" class=\"productImg\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2020\/04\/AL5050-Aluminium_tape-50mm_x_50m-5425014223026-HPX.jpg\" \/><\/p>\n<h2>ALUMINIUM TAPE<\/h2>\n<div class=\"applications\"><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/ALUMINIUM_tape-Detail.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/ALUMINIUM_tape-Detail.jpg\" alt=\"\" width=\"2000\" height=\"2000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/ALUMINIUM_tape-Wall.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/ALUMINIUM_tape-Wall.jpg\" alt=\"\" width=\"1000\" height=\"1000\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Alu_tape-Icon_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Alu_tape-Icon_2.jpg\" alt=\"\" width=\"591\" height=\"591\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Cold_Weather_Kleefstof.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Cold_Weather_Adhesive.jpg\" alt=\"\" width=\"591\" height=\"591\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Temp_max-120_c-min_-30_c.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Temp_max-120_c-min_-30_c.jpg\" alt=\"\" width=\"591\" height=\"591\" \/><\/a><a href=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Thickness_40\u00b5m.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/hpx.eu\/wp-content\/uploads\/2021\/05\/Thickness_40\u00b5m.jpg\" alt=\"\" width=\"591\" height=\"591\" \/><\/a><\/div>\n<ul class=\"product_UPS\">\n<li>Cinta de aluminio para reparar, sellar, unir metal<\/li>\n<li>Cinta fuerte, adecuada para un pegado temporal o permanente en circunstancias extremas<\/li>\n<\/ul>\n<ul class=\"secondary_USPs\">\n<li>Tambien puede seer aplicada con temperatura baja<\/li>\n<li>Excelente durabilidad y resistencia al desgaste<\/li>\n<li>Ideal para conectar y sellar paneles aislantes<\/li>\n<li>Para uso interior y exterior<\/li>\n<\/ul>\n<table class=\"product_table\">\n<thead>\n<tr>\n<th>Art. N\u00b0<\/th>\n<th>Anchura<\/th>\n<th>Longitud<\/th>\n<th>Color<\/th>\n<th>Paq.<\/th>\n<th>Codigo de EAN<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>AL5010<\/td>\n<td>50 mm<\/td>\n<td>10 m<\/td>\n<td>aluminium<\/td>\n<td>54<\/td>\n<td>5407004560113<\/td>\n<\/tr>\n<tr>\n<td>AL5050<\/td>\n<td>50 mm<\/td>\n<td>50 m<\/td>\n<td>aluminium<\/td>\n<td>24<\/td>\n<td>5425014223026<\/td>\n<\/tr>\n<tr>\n<td>AL7550<\/td>\n<td>75 mm<\/td>\n<td>50 m<\/td>\n<td>aluminium<\/td>\n<td>16<\/td>\n<td>5425014224238<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"product_characteristics\">\n        <b>Adhesivo: <\/b>acrilico solvente<br \/>\n        <b>Soporte: <\/b>aluminio<br \/>\n        <b>Temperatura maxima: <\/b>120\u00b0C<br \/>\n        <b>Resistencia a la traccion: <\/b>55 N\/25 mm<br \/>\n        <b>Fuerza adhesiva: <\/b>20 N\/25 mm<br \/>\n        <b>Grosor: <\/b>0,08 mm\n    <\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DURABLE AIRTIGHT PRODUCTS AIRTIGHT Flex AIRTIGHT Flex AIRTIGHT Flex Go AIRTIGHT Flex Go AIRTIGHT UV AIRTIGHT UV AIRTIGHT UV AIRTIGHT Indoor AIRTIGHT Indoor AIRTIGHT Roof AIRTIGHT Fix AIRTIGHT FLEX AIRTIGHT FLEX AIRTIGHT FLEX GO AIRTIGHT FLEX GO AIRTIGHT UV AIRTIGHT UV AIRTIGHT UV AIRTIGHT INDOOR AIRTIGHT INDOOR AIRTIGHT ROOF AIRTIGHT FIX \u00bfPor qu\u00e9 construir de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-108617","page","type-page","status-publish","hentry","post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DURABLE AIRTIGHT PRODUCTS - HPX<\/title>\n<meta name=\"description\" content=\"Los productos herm\u00e9ticos y duraderos de HPX son una selecci\u00f3n de cintas autoadhesivas profesionales para el sellado de viviendas y edificios.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DURABLE AIRTIGHT PRODUCTS - HPX\" \/>\n<meta property=\"og:description\" content=\"Los productos herm\u00e9ticos y duraderos de HPX son una selecci\u00f3n de cintas autoadhesivas profesionales para el sellado de viviendas y edificios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hpx.eu\/es\/durable-airtight-products\/\" \/>\n<meta property=\"og:site_name\" content=\"HPX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HPXtape\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T07:34:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/mobileOverview-2025.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/\",\"url\":\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/\",\"name\":\"DURABLE AIRTIGHT PRODUCTS - HPX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hpx.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/mobileOverview-2025.jpg\",\"datePublished\":\"2021-05-20T13:48:40+00:00\",\"dateModified\":\"2025-10-24T07:34:02+00:00\",\"description\":\"Los productos herm\u00e9ticos y duraderos de HPX son una selecci\u00f3n de cintas autoadhesivas profesionales para el sellado de viviendas y edificios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hpx.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/mobileOverview-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/hpx.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/mobileOverview-2025.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hpx.eu\\\/es\\\/durable-airtight-products\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hpx.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DURABLE AIRTIGHT PRODUCTS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/hpx.eu\\\/es\\\/\",\"name\":\"HPX\",\"description\":\"Tough Job, Tougher Tape\",\"publisher\":{\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/hpx.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#organization\",\"name\":\"Option Tape Specialties\",\"url\":\"http:\\\/\\\/hpx.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Option Tape Specialties\"},\"image\":{\"@id\":\"http:\\\/\\\/hpx.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HPXtape\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2913311\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCCYnFjBGfKw8SPW1hMUCVFg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DURABLE AIRTIGHT PRODUCTS - HPX","description":"Los productos herm\u00e9ticos y duraderos de HPX son una selecci\u00f3n de cintas autoadhesivas profesionales para el sellado de viviendas y edificios.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"DURABLE AIRTIGHT PRODUCTS - HPX","og_description":"Los productos herm\u00e9ticos y duraderos de HPX son una selecci\u00f3n de cintas autoadhesivas profesionales para el sellado de viviendas y edificios.","og_url":"https:\/\/hpx.eu\/es\/durable-airtight-products\/","og_site_name":"HPX","article_publisher":"https:\/\/www.facebook.com\/HPXtape\/","article_modified_time":"2025-10-24T07:34:02+00:00","og_image":[{"url":"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/mobileOverview-2025.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hpx.eu\/es\/durable-airtight-products\/","url":"https:\/\/hpx.eu\/es\/durable-airtight-products\/","name":"DURABLE AIRTIGHT PRODUCTS - HPX","isPartOf":{"@id":"https:\/\/hpx.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hpx.eu\/es\/durable-airtight-products\/#primaryimage"},"image":{"@id":"https:\/\/hpx.eu\/es\/durable-airtight-products\/#primaryimage"},"thumbnailUrl":"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/mobileOverview-2025.jpg","datePublished":"2021-05-20T13:48:40+00:00","dateModified":"2025-10-24T07:34:02+00:00","description":"Los productos herm\u00e9ticos y duraderos de HPX son una selecci\u00f3n de cintas autoadhesivas profesionales para el sellado de viviendas y edificios.","breadcrumb":{"@id":"https:\/\/hpx.eu\/es\/durable-airtight-products\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hpx.eu\/es\/durable-airtight-products\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hpx.eu\/es\/durable-airtight-products\/#primaryimage","url":"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/mobileOverview-2025.jpg","contentUrl":"https:\/\/hpx.eu\/wp-content\/uploads\/2025\/10\/mobileOverview-2025.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/hpx.eu\/es\/durable-airtight-products\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hpx.eu\/es\/"},{"@type":"ListItem","position":2,"name":"DURABLE AIRTIGHT PRODUCTS"}]},{"@type":"WebSite","@id":"https:\/\/hpx.eu\/es\/#website","url":"https:\/\/hpx.eu\/es\/","name":"HPX","description":"Tough Job, Tougher Tape","publisher":{"@id":"https:\/\/hpx.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hpx.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hpx.eu\/es\/#organization","name":"Option Tape Specialties","url":"https:\/\/hpx.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hpx.eu\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Option Tape Specialties"},"image":{"@id":"https:\/\/hpx.eu\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HPXtape\/","https:\/\/www.linkedin.com\/company\/2913311\/","https:\/\/www.youtube.com\/channel\/UCCYnFjBGfKw8SPW1hMUCVFg"]}]}},"_links":{"self":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/pages\/108617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/comments?post=108617"}],"version-history":[{"count":5,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/pages\/108617\/revisions"}],"predecessor-version":[{"id":180519,"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/pages\/108617\/revisions\/180519"}],"wp:attachment":[{"href":"https:\/\/hpx.eu\/es\/wp-json\/wp\/v2\/media?parent=108617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}